{"id":73792,"date":"2019-06-28T10:04:24","date_gmt":"2019-06-28T10:04:24","guid":{"rendered":"http:\/\/blog.ivoox.com\/?p=73792"},"modified":"2022-04-04T15:43:35","modified_gmt":"2022-04-04T13:43:35","slug":"la-comunidad-disponible-tambien-en-ios","status":"publish","type":"post","link":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/","title":{"rendered":"La Comunidad, disponible tambi\u00e9n en iOS"},"content":{"rendered":"<div class=\"ivoox-post-content\"><div class=\"ivoox-post-index\" id=\"table-content\"><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#%C2%A1La_Comunidad_llega_a_iOS\" >\u00a1La Comunidad llega a iOS!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#Nuevas_funcionalidades_Premium\" >Nuevas funcionalidades Premium<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#Correccion_de_errores\" >Correcci\u00f3n de errores<\/a><\/li><\/ul><\/nav><\/div>\n<\/div><div class=\"ivoox-post-body\">\n\t\t\n\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t<a class=\"post-thumbnail-inner alignwide\" href=\"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/\" aria-hidden=\"true\" tabindex=\"-1\">\n\t\t\t\t\t<img width=\"1200\" height=\"675\" src=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"La Comunidad, disponible tambi\u00e9n en iOS\" srcset=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png 1200w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3-300x169.png 300w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3-1024x576.png 1024w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3-768x432.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" style=\"width:100%;height:56.25%;max-width:1200px;\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<figcaption class=\"wp-caption-text\">La Comunidad, disponible tambi\u00e9n en iOS<\/figcaption>\n\t\t\t\t\t\t\t<\/figure><!-- .post-thumbnail -->\n\n\t\t\t\t\n<p class=\"has-text-align-left\"><span style=\"font-weight: 400;\">Llega el verano, estaci\u00f3n de calor, de terrazas llenas, de piscina y de playa. Llegan las vacaciones, ese momento tan esperado durante todo el a\u00f1o con el que por fin podemos descansar y relajarnos. \u00bfY qu\u00e9 mejor para disfrutar de nuestro tiempo libre que escuchar a nuestros podcasters favoritos? Desempolven el cuaderno por \u00faltima vez durante este a\u00f1o y saquen papel y boli, porque traemos novedades con esta <\/span><b>nueva actualizaci\u00f3n de iOS <\/b><span style=\"font-weight: 400;\">que acabamos de lanzar, que seguro que no os dejar\u00e1n indiferentes.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"la-comunidad-llega-a-ios\"><span class=\"ez-toc-section\" id=\"%C2%A1La_Comunidad_llega_a_iOS\"><\/span>\u00a1La Comunidad llega a iOS! <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\"><strong>Con la versi\u00f3n 3.27 la Comunidad est\u00e1 disponible en iOS<\/strong>. Con esta funcionalidad, que muchos ya conoc\u00e9is porque ya estaba disponible tanto en <a href=\"https:\/\/ivoox.zendesk.com\/hc\/es-es\/articles\/360000559717--Qu%C3%A9-es-la-Comunidad-de-mi-Podcast-\" target=\"_blank\" rel=\"noopener\">Web<\/a> <\/span><span style=\"font-weight: 400;\">como en <a href=\"https:\/\/blog.ivoox.com\/llega-la-comunidad-de-podcast-a-android_0073148\/\" target=\"_blank\" rel=\"noopener\">Android<\/a>,<\/span><span style=\"font-weight: 400;\">&nbsp;los podcasters tienen la posibilidad de compartir contenido en diferentes formatos multimedia con todos vosotros. <\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Como oyentes <strong>podr\u00e9is interactuar con vuestros podcasters preferidos de una forma mucho m\u00e1s pr\u00f3xima<\/strong>, participando en hilos de conversaci\u00f3n y comentando vuestras opiniones e impresiones. Asimismo, podr\u00e9is estar al tanto de su actividad en redes sociales y de todas las novedades que vayan publicando.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Hilos-comunidad-iOS-OKOK.mp4\"><\/video><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">En el caso de estar apoyando un podcast, tendr\u00e9is acceso a <strong>posts con informaci\u00f3n exclusiva para mecenas<\/strong>.<\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Apoyos-LODE.jpg\" alt=\"\" class=\"wp-image-73794\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Apoyos-LODE.jpg 957w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Apoyos-LODE-300x300.jpg 300w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Apoyos-LODE-150x150.jpg 150w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Apoyos-LODE-768x768.jpg 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nuevas-funcionalidades-premium\"><span class=\"ez-toc-section\" id=\"Nuevas_funcionalidades_Premium\"><\/span>Nuevas funcionalidades Premium <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Nos gusta escuchar vuestras sugerencias y comentarios, y es por ello que hemos a\u00f1adido <strong>dos nuevas funcionalidades<\/strong> que nos hab\u00edais pedido en m\u00e1s de una ocasi\u00f3n, y que estar\u00e1n disponibles con el servicio Premium en iOS:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong><em>Boost<\/em> de volumen<\/strong>: \u00bfOs pasa que a veces ten\u00e9is dificultades para seguir la conversaci\u00f3n de un audio cuando vais en el metro o pas\u00e1is por al lado de unas obras?&nbsp;<\/span>\u00a1Desde la ficha de reproducci\u00f3n de cualquier episodio podr\u00e9is solventarlo marcando la opci\u00f3n de \u201c<strong>Potenciar volumen del audio<\/strong>\u201d.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/boost-volumen.png\" alt=\"\" class=\"wp-image-73795\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/boost-volumen.png 957w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/boost-volumen-300x300.png 300w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/boost-volumen-150x150.png 150w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/boost-volumen-768x768.png 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong>Sincronizaci\u00f3n entre dispositivos<\/strong>: Cambia del m\u00f3vil a la tablet o al ordenador y a la inversa sin tener que preocuparte. \u00a1<strong>Reprende el audio en el mismo punto<\/strong> en el que te hab\u00edas quedado cuando dejaste de escucharlo <strong>desde otros dispositivos<\/strong>!<\/span><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"600\" src=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/punto-de-escucha.png\" alt=\"\" class=\"wp-image-73796\" srcset=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/punto-de-escucha.png 1200w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/punto-de-escucha-300x150.png 300w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/punto-de-escucha-1024x512.png 1024w, https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/punto-de-escucha-768x384.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/div>\n\n\n\n<p><strong><em>\u00bfY el nuevo dise\u00f1o de Android para cu\u00e1ndo?<\/em><\/strong> Tened paciencia, estamos ultimando detalles para poder lanzar la siguiente versi\u00f3n de este sistema operativo, y muy pronto estar\u00e1 disponible. Se trata de un proyecto grande y queremos que est\u00e9 todo perfecto para el momento de su lanzamiento. \u00a1Estad atentos a nuestras comunicaciones porque se trata de la actualizaci\u00f3n m\u00e1s grande que hemos preparado hasta el momento!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"correccion-de-errores\"><span class=\"ez-toc-section\" id=\"Correccion_de_errores\"><\/span>Correcci\u00f3n de errores<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Gracias a vuestro <em>feedback<\/em> hemos podido&nbsp;solucionar el error de que el carrusel de radios relacionadas se quedaba en blanco en algunas situaciones, detectado en la versi\u00f3n 3.25.6.<\/span><\/p>\n<\/div><div class=\"ivoox-post-banners\">\n<div class=\"banner-card\">\n\t<img src=\"https:\/\/www.ivoox.com\/blog\/wp-content\/themes\/ivoox-theme\/assets\/images\/banner-ivoox-app-r25.jpg\" alt=\"Descarga la app\" width=\"325\" height=\"260\" class=\"banner-image\">\n\t<div class=\"banner-content\">\n\t\t<h3>\n\t\t\tDescarga gratis la <span>app de iVoox<\/span>\n\t\t<\/h3>\n\t\t<p>\n\t\t\tEscucha cuando y donde quieras tus podcasts, radios y audiolibros favoritos.\n\t\t<\/p>\n\t\t<a href=\"https:\/\/www.ivoox.com\/_ik_descarga-app_1.html?utm_source%3Dbanner%26utm_medium%3Dweb%26utm_content%3Ddescargar_app%26utm_campaign%3Dblog\" target=\"blank\" class=\"btn\">Descargar gratis<\/a>\t<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Con la nueva actualizaci\u00f3n de iOS la Comunidad ya est\u00e1 disponible para este sistema operativo. \u00a1Conoce todas las novedades!<\/p>\n","protected":false},"author":6,"featured_media":80657,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-73792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuevas-funcionalidades","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Comunidad, disponible tambi\u00e9n en iOS - iVoox Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Comunidad, disponible tambi\u00e9n en iOS - iVoox Blog\" \/>\n<meta property=\"og:description\" content=\"Con la nueva actualizaci\u00f3n de iOS la Comunidad ya est\u00e1 disponible para este sistema operativo. \u00a1Conoce todas las novedades!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/\" \/>\n<meta property=\"og:site_name\" content=\"iVoox Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-28T10:04:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T13:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pedro Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Comunidad, disponible tambi\u00e9n en iOS - iVoox Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/","og_locale":"es_ES","og_type":"article","og_title":"La Comunidad, disponible tambi\u00e9n en iOS - iVoox Blog","og_description":"Con la nueva actualizaci\u00f3n de iOS la Comunidad ya est\u00e1 disponible para este sistema operativo. \u00a1Conoce todas las novedades!","og_url":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/","og_site_name":"iVoox Blog","article_published_time":"2019-06-28T10:04:24+00:00","article_modified_time":"2022-04-04T13:43:35+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png","type":"image\/png"}],"author":"Pedro Mart\u00ednez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pedro Mart\u00ednez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#article","isPartOf":{"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/"},"author":{"name":"Pedro Mart\u00ednez","@id":"https:\/\/www.ivoox.com\/blog\/#\/schema\/person\/a8a3150fffe39ede014ac2b2014def05"},"headline":"La Comunidad, disponible tambi\u00e9n en iOS","datePublished":"2019-06-28T10:04:24+00:00","dateModified":"2022-04-04T13:43:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/www.ivoox.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png","articleSection":["Nuevas funcionalidades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/","url":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/","name":"La Comunidad, disponible tambi\u00e9n en iOS - iVoox Blog","isPartOf":{"@id":"https:\/\/www.ivoox.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#primaryimage"},"image":{"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png","datePublished":"2019-06-28T10:04:24+00:00","dateModified":"2022-04-04T13:43:35+00:00","breadcrumb":{"@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#primaryimage","url":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png","contentUrl":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2019\/06\/Comunidad-en-iOS-3.png","width":1200,"height":675,"caption":"La Comunidad, disponible tambi\u00e9n en iOS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ivoox.com\/blog\/la-comunidad-disponible-tambien-en-ios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ivoox.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La Comunidad, disponible tambi\u00e9n en iOS"}]},{"@type":"WebSite","@id":"https:\/\/www.ivoox.com\/blog\/#website","url":"https:\/\/www.ivoox.com\/blog\/","name":"iVoox Blog","description":"\u00daltimas noticias de iVoox","publisher":{"@id":"https:\/\/www.ivoox.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ivoox.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ivoox.com\/blog\/#organization","name":"iVoox Blog","url":"https:\/\/www.ivoox.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ivoox.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2022\/02\/1x1.png","contentUrl":"https:\/\/www.ivoox.com\/blog\/wp-content\/uploads\/2022\/02\/1x1.png","width":1,"height":1,"caption":"iVoox Blog"},"image":{"@id":"https:\/\/www.ivoox.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ivoox.com\/blog\/#\/schema\/person\/a8a3150fffe39ede014ac2b2014def05","name":"Pedro Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ivoox.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/692b2b53e1bb68d8f07b66f5ff9e37b147d3ab6007c13ccdb1e2b28c68af7e1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/692b2b53e1bb68d8f07b66f5ff9e37b147d3ab6007c13ccdb1e2b28c68af7e1d?s=96&d=mm&r=g","caption":"Pedro Mart\u00ednez"},"description":"Ayudando en el equipo de Marketing y Contenidos de iVoox. Algunos de mis podcasts favoritos son: Roma Aeterna, La Ruina y Cr\u00f3nicas de la Calle Morgue.","url":"https:\/\/www.ivoox.com\/blog\/author\/pedro-martinez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/posts\/73792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/comments?post=73792"}],"version-history":[{"count":1,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/posts\/73792\/revisions"}],"predecessor-version":[{"id":80653,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/posts\/73792\/revisions\/80653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/media\/80657"}],"wp:attachment":[{"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/media?parent=73792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/categories?post=73792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ivoox.com\/blog\/wp-json\/wp\/v2\/tags?post=73792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}